{"id":271809,"date":"2021-04-06T05:00:00","date_gmt":"2021-04-06T10:00:00","guid":{"rendered":"http:\/\/my.dev.vanderbilt.edu\/richardpeek\/?guid=2e1296b8b99970a6b1edb97522a87f11"},"modified":"2021-04-29T10:00:00","modified_gmt":"2021-04-29T15:00:00","slug":"table-of-contents-67","status":"publish","type":"post","link":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/2021\/04\/table-of-contents-67\/","title":{"rendered":"Table of Contents"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3889,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-271809","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts\/271809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/users\/3889"}],"replies":[{"embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/comments?post=271809"}],"version-history":[{"count":140,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts\/271809\/revisions"}],"predecessor-version":[{"id":274336,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts\/271809\/revisions\/274336"}],"wp:attachment":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/media?parent=271809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/categories?post=271809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/tags?post=271809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}