{"id":217946,"date":"2020-07-22T14:00:00","date_gmt":"2020-07-22T19:00:00","guid":{"rendered":"http:\/\/my.dev.vanderbilt.edu\/richardpeek\/?guid=e892499e34d21f0e0b940ec172916796"},"modified":"2020-07-31T20:00:00","modified_gmt":"2020-08-01T01:00:00","slug":"elsewhere-in-the-aga-journals-45","status":"publish","type":"post","link":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/2020\/07\/elsewhere-in-the-aga-journals-45\/","title":{"rendered":"Elsewhere in The AGA Journals"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3889,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-217946","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts\/217946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/users\/3889"}],"replies":[{"embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/comments?post=217946"}],"version-history":[{"count":174,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts\/217946\/revisions"}],"predecessor-version":[{"id":218893,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/posts\/217946\/revisions\/218893"}],"wp:attachment":[{"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/media?parent=217946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/categories?post=217946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/richardpeek\/wp-json\/wp\/v2\/tags?post=217946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}