{"id":53,"count":3,"description":"","link":"https:\/\/my.dev.vanderbilt.edu\/heimat\/category\/aufsatze-f14\/aufsatz1-f14\/","name":"Aufsatz 1 (F14) - Was bedeutet \"Heimat\" f\u00fcr Sie? Wo sind Sie zuhause?","slug":"aufsatz1-f14","taxonomy":"category","parent":54,"meta":[],"_links":{"self":[{"href":"https:\/\/my.dev.vanderbilt.edu\/heimat\/wp-json\/wp\/v2\/categories\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my.dev.vanderbilt.edu\/heimat\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/my.dev.vanderbilt.edu\/heimat\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/my.dev.vanderbilt.edu\/heimat\/wp-json\/wp\/v2\/categories\/54"}],"wp:post_type":[{"href":"https:\/\/my.dev.vanderbilt.edu\/heimat\/wp-json\/wp\/v2\/posts?categories=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}